{"id":24496,"date":"2026-06-25T15:52:17","date_gmt":"2026-06-25T15:52:17","guid":{"rendered":"https:\/\/www.eurekacolour.com\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/"},"modified":"2026-06-26T07:42:43","modified_gmt":"2026-06-26T07:42:43","slug":"fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2","status":"publish","type":"post","link":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/","title":{"rendered":"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":21722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fire-retardant paint for wood: how to navigate regulations and fire reaction classes - Eureka Colour<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes - Eureka Colour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Eureka Colour\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eurekacoloursrl\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T15:52:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T07:42:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/12\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#\\\/schema\\\/person\\\/c3352905b98ba601b1f4f4bcf42cd5a6\"},\"headline\":\"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes\",\"datePublished\":\"2026-06-25T15:52:17+00:00\",\"dateModified\":\"2026-06-26T07:42:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eurekacolour.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg\",\"articleSection\":[\"Senza categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/\",\"url\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/\",\"name\":\"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes - Eureka Colour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eurekacolour.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg\",\"datePublished\":\"2026-06-25T15:52:17+00:00\",\"dateModified\":\"2026-06-26T07:42:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eurekacolour.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eurekacolour.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Storage of Eureka Colour fire-retardant paint buckets\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/\",\"name\":\"Eureka Colour\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#organization\",\"name\":\"Eureka Colour\",\"url\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eurekacolour.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo3.svg\",\"contentUrl\":\"https:\\\/\\\/www.eurekacolour.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo3.svg\",\"width\":486,\"height\":91,\"caption\":\"Eureka Colour\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eurekacoloursrl\\\/\",\"https:\\\/\\\/www.instagram.com\\\/eurekacolour\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/#\\\/schema\\\/person\\\/c3352905b98ba601b1f4f4bcf42cd5a6\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad43babd747106539aaa86fc27251c6fd5d4219f6f34034a0059ecb43ba89a70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad43babd747106539aaa86fc27251c6fd5d4219f6f34034a0059ecb43ba89a70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad43babd747106539aaa86fc27251c6fd5d4219f6f34034a0059ecb43ba89a70?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/demo.springadv.it\\\/wordpress\"],\"url\":\"https:\\\/\\\/www.eurekacolour.com\\\/en\\\/author\\\/spring\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes - Eureka Colour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/","og_locale":"en_US","og_type":"article","og_title":"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes - Eureka Colour","og_url":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/","og_site_name":"Eureka Colour","article_publisher":"https:\/\/www.facebook.com\/eurekacoloursrl\/","article_published_time":"2026-06-25T15:52:17+00:00","article_modified_time":"2026-06-26T07:42:43+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/12\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#article","isPartOf":{"@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/"},"author":{"name":"admin","@id":"https:\/\/www.eurekacolour.com\/en\/#\/schema\/person\/c3352905b98ba601b1f4f4bcf42cd5a6"},"headline":"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes","datePublished":"2026-06-25T15:52:17+00:00","dateModified":"2026-06-26T07:42:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/"},"wordCount":12,"publisher":{"@id":"https:\/\/www.eurekacolour.com\/en\/#organization"},"image":{"@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/12\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg","articleSection":["Senza categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/","url":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/","name":"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes - Eureka Colour","isPartOf":{"@id":"https:\/\/www.eurekacolour.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#primaryimage"},"image":{"@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/12\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg","datePublished":"2026-06-25T15:52:17+00:00","dateModified":"2026-06-26T07:42:43+00:00","breadcrumb":{"@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#primaryimage","url":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/12\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg","contentUrl":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/12\/vernici-ignifughe-legno-arredo-eureka-colour-veneto.jpg","width":1920,"height":1280,"caption":"Storage of Eureka Colour fire-retardant paint buckets"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eurekacolour.com\/en\/fire-retardant-paint-for-wood-how-to-navigate-regulations-and-fire-reaction-classes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eurekacolour.com\/en\/"},{"@type":"ListItem","position":2,"name":"Fire-retardant paint for wood: how to navigate regulations and fire reaction classes"}]},{"@type":"WebSite","@id":"https:\/\/www.eurekacolour.com\/en\/#website","url":"https:\/\/www.eurekacolour.com\/en\/","name":"Eureka Colour","description":"","publisher":{"@id":"https:\/\/www.eurekacolour.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eurekacolour.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eurekacolour.com\/en\/#organization","name":"Eureka Colour","url":"https:\/\/www.eurekacolour.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eurekacolour.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/07\/logo3.svg","contentUrl":"https:\/\/www.eurekacolour.com\/wp-content\/uploads\/2025\/07\/logo3.svg","width":486,"height":91,"caption":"Eureka Colour"},"image":{"@id":"https:\/\/www.eurekacolour.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eurekacoloursrl\/","https:\/\/www.instagram.com\/eurekacolour\/"]},{"@type":"Person","@id":"https:\/\/www.eurekacolour.com\/en\/#\/schema\/person\/c3352905b98ba601b1f4f4bcf42cd5a6","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ad43babd747106539aaa86fc27251c6fd5d4219f6f34034a0059ecb43ba89a70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad43babd747106539aaa86fc27251c6fd5d4219f6f34034a0059ecb43ba89a70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad43babd747106539aaa86fc27251c6fd5d4219f6f34034a0059ecb43ba89a70?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/demo.springadv.it\/wordpress"],"url":"https:\/\/www.eurekacolour.com\/en\/author\/spring\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/posts\/24496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/comments?post=24496"}],"version-history":[{"count":1,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/posts\/24496\/revisions"}],"predecessor-version":[{"id":24498,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/posts\/24496\/revisions\/24498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/media\/21722"}],"wp:attachment":[{"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/media?parent=24496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/categories?post=24496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eurekacolour.com\/en\/wp-json\/wp\/v2\/tags?post=24496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}